{"id":1669,"count":1,"description":"","link":"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba","name":"elektr\u012bba","slug":"elektriba","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>elektr\u012bba Archives - Baltic Course<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"elektr\u012bba Archives - Baltic Course\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba\" \/>\n<meta property=\"og:site_name\" content=\"Baltic Course\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.baltic-course.com\\\/lv\\\/tag\\\/elektriba\",\"url\":\"https:\\\/\\\/www.baltic-course.com\\\/lv\\\/tag\\\/elektriba\",\"name\":\"elektr\u012bba Archives - Baltic Course\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.baltic-course.com\\\/lv\\\/tag\\\/elektriba#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.baltic-course.com\\\/lv\\\/tag\\\/elektriba#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"elektr\u012bba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/#website\",\"url\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/\",\"name\":\"Baltic Course\",\"description\":\"Notikumi, izklaide un padomi\",\"publisher\":{\"@id\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/#organization\",\"name\":\"Baltic Course\",\"url\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.baltic-course.com\\\/lv\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-baltic-course-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.baltic-course.com\\\/lv\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-baltic-course-3.jpg\",\"width\":810,\"height\":151,\"caption\":\"Baltic Course\"},\"image\":{\"@id\":\"https:\\\/\\\/baltic-course.com\\\/lv\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"elektr\u012bba Archives - Baltic Course","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba","og_locale":"en_GB","og_type":"article","og_title":"elektr\u012bba Archives - Baltic Course","og_url":"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba","og_site_name":"Baltic Course","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba","url":"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba","name":"elektr\u012bba Archives - Baltic Course","isPartOf":{"@id":"https:\/\/baltic-course.com\/lv\/#website"},"breadcrumb":{"@id":"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.baltic-course.com\/lv\/tag\/elektriba#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/baltic-course.com\/lv\/"},{"@type":"ListItem","position":2,"name":"elektr\u012bba"}]},{"@type":"WebSite","@id":"https:\/\/baltic-course.com\/lv\/#website","url":"https:\/\/baltic-course.com\/lv\/","name":"Baltic Course","description":"Notikumi, izklaide un padomi","publisher":{"@id":"https:\/\/baltic-course.com\/lv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/baltic-course.com\/lv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/baltic-course.com\/lv\/#organization","name":"Baltic Course","url":"https:\/\/baltic-course.com\/lv\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/baltic-course.com\/lv\/#\/schema\/logo\/image\/","url":"https:\/\/www.baltic-course.com\/lv\/wp-content\/uploads\/2023\/11\/cropped-baltic-course-3.jpg","contentUrl":"https:\/\/www.baltic-course.com\/lv\/wp-content\/uploads\/2023\/11\/cropped-baltic-course-3.jpg","width":810,"height":151,"caption":"Baltic Course"},"image":{"@id":"https:\/\/baltic-course.com\/lv\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.baltic-course.com\/lv\/wp-json\/wp\/v2\/tags\/1669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.baltic-course.com\/lv\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.baltic-course.com\/lv\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.baltic-course.com\/lv\/wp-json\/wp\/v2\/posts?tags=1669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}